{"id":825,"date":"2019-04-24T22:43:36","date_gmt":"2019-04-24T20:43:36","guid":{"rendered":"https:\/\/www.casaldoumia.com\/?p=825"},"modified":"2020-01-29T22:38:07","modified_gmt":"2020-01-29T21:38:07","slug":"visita-casal-do-umia-2019","status":"publish","type":"post","link":"https:\/\/www.casaldoumia.com\/en\/visita-casal-do-umia-2019\/","title":{"rendered":"Visita a Casal do Umia"},"content":{"rendered":"<p>Personalidades del \u00e1mbito nacional y local nos visitan desde diversos lugares del pa\u00eds para disfrutar de nuestra exquisita comida y de nuestra esmerada atenci\u00f3n.<\/p>\n<p>Nosotros en Casal do Umia tambi\u00e9n disfrutamos al ver su satisfacci\u00f3n por la calidad de nuestra cocina, nuestras instalaciones y los diversos servicios que gustosamente aqu\u00ed ofrecemos, \u00a1gracias por visitarnos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personalidades del \u00e1mbito nacional y local nos visitan desde diversos lugares del pa\u00eds para disfrutar de nuestra exquisita comida y de nuestra esmerada atenci\u00f3n. Nosotros en Casal do Umia tambi\u00e9n disfrutamos al ver su satisfacci\u00f3n por la calidad de nuestra cocina, nuestras instalaciones y los diversos servicios que gustosamente aqu\u00ed ofrecemos, \u00a1gracias por visitarnos!<\/p>\n","protected":false},"author":2,"featured_media":826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/posts\/825"}],"collection":[{"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":2,"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"predecessor-version":[{"id":828,"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/posts\/825\/revisions\/828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/media\/826"}],"wp:attachment":[{"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.casaldoumia.com\/en\/wp-json\/wp\/v2\/tags?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}